{"id":11210,"date":"2025-07-30T09:00:18","date_gmt":"2025-07-30T07:00:18","guid":{"rendered":"https:\/\/strail.de\/?page_id=11210"},"modified":"2026-06-02T09:44:05","modified_gmt":"2026-06-02T07:44:05","slug":"edge","status":"publish","type":"page","link":"https:\/\/strail.de\/it\/sistemi-di-attraversamento-a-raso\/soluzioni-speciali\/edge\/","title":{"rendered":"edge"},"content":{"rendered":"<div class=\"wp-block-columns hero_subpages has-accent-2-background-color has-background is-layout-flex wp-container-core-columns-is-layout-e8e13fa1 wp-block-columns-is-layout-flex\" style=\"margin-bottom:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-column is-vertically-aligned-stretch is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-cover\" style=\"border-radius:0px;min-height:100%;aspect-ratio:unset;\"><img alt=\"edge - Barrierefreie Bahnsteigkante aus Gummi f\u00fcr mehr Komfort und Schutz\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/10\/edge-500x375.jpg\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/10\/edge.jpg 1333w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/10\/edge-300x225.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/10\/edge-1000x750.jpg 1000w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/10\/edge-500x375.jpg 500w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" class=\"wp-block-cover__image-background wp-image-1809 size-full\" width=\"500\" height=\"\" decoding=\"async\" fetchpriority=\"high\" data-object-fit=\"cover\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#5e5c60\"><\/span><div class=\"wp-block-cover__inner-container has-global-padding is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size\"><\/p>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch has-global-padding is-content-justification-right is-layout-constrained wp-container-core-column-is-layout-86f7cfa0 wp-block-column-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--spalten-gap-standart);padding-right:0;padding-bottom:var(--wp--preset--spacing--spalten-gap-standart);padding-left:0;flex-basis:50%\">\n<div class=\"wp-block-group is-layout-flow wp-container-core-group-is-layout-15feb225 wp-block-group-is-layout-flow\" style=\"padding-right:var(--wp--preset--spacing--hero-spalten);padding-left:var(--wp--preset--spacing--200)\">\n<h1 class=\"wp-block-heading\">edge<\/h1>\n\n\n\n<p><strong>Profilo in gomma per banchine di fermata senza barriere, per maggiore comfort e protezione<\/strong><\/p>\n\n\n\n<p>edge \u00e8 un profilo in gomma per banchine sviluppato appositamente per le fermate dei trasporti pubblici. Permette di salire e scendere in modo confortevole e senza barriere, anche con diversi tipi di veicoli e geometrie di piattaforma. Il materiale flessibile protegge i gradini scorrevoli e le carrozzerie dei veicoli, riducendo i danni e i costi di manutenzione. Il montaggio \u00e8 semplice e veloce, anche nelle sedi urbane pi\u00f9 inaccessibili. \u00c8 possibile anche un uso combinato con gli autobus, alle apposite fermate.    <\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns are-vertically-aligned-center kachelslider is-layout-flex wp-container-core-columns-is-layout-9c22b1e3 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group product_img_slider- thumbnailnav hand-1 mob-1 slider-gap-16 noloop lightbox is-layout-grid wp-container-core-group-is-layout-478b6e6b wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-full wp-container-content-69bc4bdf\"><img decoding=\"async\" width=\"1400\" height=\"1000\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/edge-Kamera-3.jpg\" alt=\"edge immagine 3D\" class=\"wp-image-6300\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/edge-Kamera-3.jpg 1400w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/edge-Kamera-3-300x214.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/edge-Kamera-3-1000x714.jpg 1000w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/edge-Kamera-3-500x357.jpg 500w\" sizes=\"(max-width: 480px) 150px, (max-width: 767px) 150px, (max-width: 1399px) 600px, (max-width: 1999px) 700px, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full wp-container-content-69bc4bdf\"><img decoding=\"async\" width=\"1196\" height=\"1471\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante-1.jpg\" alt=\"edge profilo in gomma per banchine di fermata, per maggiore comfort e protezione\" class=\"wp-image-4083\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante-1.jpg 1196w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante-1-244x300.jpg 244w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante-1-813x1000.jpg 813w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante-1-500x615.jpg 500w\" sizes=\"(max-width: 480px) 150px, (max-width: 767px) 150px, (max-width: 1399px) 600px, (max-width: 1999px) 700px, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full wp-container-content-69bc4bdf\"><img decoding=\"async\" width=\"2500\" height=\"1875\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante3.jpg\" alt=\"bordo della piattaforma - bordo della piattaforma senza barriere in gomma per maggiore comfort e protezione\" class=\"wp-image-4078\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante3.jpg 2500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante3-300x225.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante3-1000x750.jpg 1000w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante3-500x375.jpg 500w\" sizes=\"(max-width: 480px) 150px, (max-width: 767px) 150px, (max-width: 1399px) 600px, (max-width: 1999px) 700px, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full wp-container-content-69bc4bdf\"><img decoding=\"async\" width=\"2500\" height=\"1875\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante4.jpg\" alt=\"Bordi della pedana Bordi della pedana accessibili in gomma per un maggiore comfort e protezione.\" class=\"wp-image-4079\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante4.jpg 2500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante4-300x225.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante4-1000x750.jpg 1000w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante4-500x375.jpg 500w\" sizes=\"(max-width: 480px) 150px, (max-width: 767px) 150px, (max-width: 1399px) 600px, (max-width: 1999px) 700px, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full wp-container-content-69bc4bdf\"><img decoding=\"async\" width=\"2500\" height=\"1875\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante2.jpg\" alt=\"edge prifolo per banchine di fermata - primo piano del profilo in gomma per banchine di fermata senza barriere, per maggiore comfort e protezione\" class=\"wp-image-4077\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante2.jpg 2500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante2-300x225.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante2-1000x750.jpg 1000w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante2-500x375.jpg 500w\" sizes=\"(max-width: 480px) 150px, (max-width: 767px) 150px, (max-width: 1399px) 600px, (max-width: 1999px) 700px, 1000px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center has-global-padding is-content-justification-left is-layout-constrained wp-container-core-column-is-layout-4987653d wp-block-column-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--spalten-gap-standart);padding-bottom:var(--wp--preset--spacing--spalten-gap-standart);flex-basis:50%\">\n<h2 class=\"wp-block-heading\" style=\"text-transform:uppercase\">Comodo, flessibile, <mark style=\"background-color:rgba(0, 0, 0, 0);color:#E65113\" class=\"has-inline-color\">sicuro<\/mark><\/h2>\n\n\n\n<p>edge ha argomenti imbattibili per convincervi: \u00e8 flessibile, resistente e facile da usare. I componenti in gomma possono essere personalizzati in base alle singole situazioni. L&#8217;elasticit\u00e0 della gomma protegge anche i veicoli e previene i danni.  <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\">Salita e discesa dalle banchine senza barriere architettoniche<\/li>\n\n\n\n<li class=\"\">Il materiale elasticizzato protegge i veicoli e i gradini scorrevoli<\/li>\n\n\n\n<li class=\"\">Adattabile a diversi raggi di curvatura e a diverse situazioni di montaggio<\/li>\n\n\n\n<li class=\"\">Adatto all&#8217;uso combinato con tram e autobus<\/li>\n\n\n\n<li class=\"\">Montaggio facile e veloce<\/li>\n\n\n\n<li class=\"\">Una soluzione durevole e a bassa manutenzione per il trasporto urbano<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n\n<section class=\"wp-block-group refs_group has-accent-2-background-color has-background has-global-padding is-layout-constrained wp-container-core-group-is-layout-c036105e wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60)\" aria-labelledby=\"referenzen-headline\">\n<div class=\"wp-block-group is-content-justification-space-between is-layout-flex wp-container-core-group-is-layout-9366075c wp-block-group-is-layout-flex\">\n<h2 class=\"wp-block-heading\" id=\"referenzen-headline\">Referenze<\/h2>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/strail.de\/it\/referenze\/\">Tutte le referenze<\/a><\/div>\n<\/div>\n<\/div>\n\n\n<div class=\"strail-posts-container refs product_img_slider scrollbar hand-1 mob-2 tab-2 desk-3 slide-1 slider-gap-16 slider-gap-mob-16 slider-gap-desk-40 noloop\" data-posts-per-page=\"6\"><div class=\"strail-post-item\" aria-labelledby=\"t-839 t-838\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname inno\">inno<\/span><span class=\"batch produktname strail\">strail<\/span><img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2026\/08\/Genova-piastra-fast-system-Overail-4-300x225.jpg\" class=\"post-thumb\" alt=\"Piano a raso d&#039;emergenza con inno a Genova, nel porto davanti alla galleria\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2026\/08\/Genova-piastra-fast-system-Overail-4-300x225.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/08\/Genova-piastra-fast-system-Overail-4-1000x750.jpg 1000w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/08\/Genova-piastra-fast-system-Overail-4-500x375.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/08\/Genova-piastra-fast-system-Overail-4.jpg 1600w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/progetto-infrastrutturale-nel-porto-di-genova-carichi-pesanti\/\">Infrastrutture nel porto di Genova: area di triage e attraversamenti a raso per elevato volume di traffico<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>Soluzione su misura realizzata nel porto di Genova: per la prima volta, il sistema di attraversamento ferroviario inno, indipendente dal passo delle traverse, \u00e8 stato utilizzato su binario fisso per area di triage davanti a una galleria. Insieme a due attraversamenti a raso strail ad alta resistenza, il progetto garantisce la massima sicurezza ed efficienza nel traffico portuale. <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/progetto-infrastrutturale-nel-porto-di-genova-carichi-pesanti\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-843\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname binario_inerbito\">Binario inerbito<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2026\/06\/Rasengleich-Kosice-300x300.jpg\" class=\"post-thumb\" alt=\"Binario inerbito del tram di Ko\u0161ice\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2026\/06\/Rasengleich-Kosice-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/06\/Rasengleich-Kosice-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/06\/Rasengleich-Kosice-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/06\/Rasengleich-Kosice.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/infrastruttura-verde-48-chilometri-di-binari-inerbiti-strailastici-in-slovacchia\/\">Infrastrutture verdi: 4,8 chilometri di binari inerbiti STRAILastic in Slovacchia<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>I requisiti ambientali stanno diventando sempre pi\u00f9 importanti nell'estensione delle reti ferroviarie urbane. In Slovacchia, il nostro sistema per binari inerbiti STRAILastic \u00e8 stato installato con successo su una lunghezza di 4,8 chilometri. Questo progetto dimostra come le moderne infrastrutture ferroviarie possano contribuire al miglioramento del microclima urbano e, allo stesso tempo, soddisfare i requisiti di isolamento dalle correnti vaganti, ventilazione delle strutture e abbattimento acustico.  <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/infrastruttura-verde-48-chilometri-di-binari-inerbiti-strailastici-in-slovacchia\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-844\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname strailway\">STRAILway<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2026\/01\/STRAILway-Brueckenbalken-Drome-Frankreich-300x300.jpg\" class=\"post-thumb\" alt=\"Traverse da ponte STRAILway in Francia\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2026\/01\/STRAILway-Brueckenbalken-Drome-Frankreich-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/01\/STRAILway-Brueckenbalken-Drome-Frankreich-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/01\/STRAILway-Brueckenbalken-Drome-Frankreich-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/01\/STRAILway-Brueckenbalken-Drome-Frankreich.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/eccellenza-ecologica-strailway-assicura-pont-bleu-sulla-drome\/\">Eccellenza ecologica: STRAILway mette in sicurezza il &#8220;Pont Bleu&#8221; sulla Dr\u00f4me<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>Nell'ambito del progetto di ristrutturazione da 70 milioni di euro della linea Livron-Aspres, SNCF R\u00e9seau ha affrontato una complessa sfida ecologica: il \"Pont Bleu\" attraversa infatti una riserva naturale rigorosamente protetta. La soluzione per coniugare la massima tutela idrica e la precisione tecnica? Le traverse polimeriche STRAILway.  <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/eccellenza-ecologica-strailway-assicura-pont-bleu-sulla-drome\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-844\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname strailway\">STRAILway<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2026\/01\/STRAILway-Brueckenbalken-Installation-Ungarn-300x300.jpg\" class=\"post-thumb\" alt=\"Traverse polimeriche STRAILway Traverse da ponte Installazione Ungheria\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2026\/01\/STRAILway-Brueckenbalken-Installation-Ungarn-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/01\/STRAILway-Brueckenbalken-Installation-Ungarn-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/01\/STRAILway-Brueckenbalken-Installation-Ungarn-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/01\/STRAILway-Brueckenbalken-Installation-Ungarn.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/commessa-ungheria-gysev-strailway-ponte\/\">Nuova commessa in Ungheria: GYSEV sceglie ancora STRAILway per la ristrutturazione di un ponte<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>Forte dei successi ottenuti a partire dal 2020, la societ\u00e0 ferroviaria ungherese GYSEV ZRt. si affida a STRAILway anche per il risanamento del ponte sul canale di marea a R\u00e9pcelak. Nel maggio 2023, le vecchie traverse da ponte in legno sono state sostituite con la moderna e durevole alternativa in materiale plastico.  <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/commessa-ungheria-gysev-strailway-ponte\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-840 t-839 t-838 all\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname strail\">strail<\/span><span class=\"batch produktname pede\">pede<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Bahnuebergang-Gluecksburger-Strasse-300x300.jpg\" class=\"post-thumb\" alt=\"Attraversamento ferroviario di Gluecksburger Strasse\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Bahnuebergang-Gluecksburger-Strasse-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Bahnuebergang-Gluecksburger-Strasse-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Bahnuebergang-Gluecksburger-Strasse-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Bahnuebergang-Gluecksburger-Strasse.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/attraversamento-a-raso\/\">Attraversamento a raso sicuro per ogni utente stradale<\/a><\/h3><div class=\"preview-text\">Dopo un'urgente opera di risanamento a Ibbenb\u00fcren, il passaggio a livello di Gl\u00fccksburger Stra\u00dfe garantisce ora la massima sicurezza per tutti gli utenti grazie a un nuovo tracciato stradale.<\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/attraversamento-a-raso\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-840 t-838 all\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname inno\">inno<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Wasserturm-Bruecke-mit-Strassenbahn-300x300.jpg\" class=\"post-thumb\" alt=\"Ponte Waassertuerm e tram\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Wasserturm-Bruecke-mit-Strassenbahn-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Wasserturm-Bruecke-mit-Strassenbahn-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Wasserturm-Bruecke-mit-Strassenbahn-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Wasserturm-Bruecke-mit-Strassenbahn.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/emergenza-traffico-e-protezione-del-deragliamento-con-inno-sul-ponte-wasserturm\/\">Corsia di emergenza e sistema antideragliamento con inno sul ponte Waassertuerm<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>Sul trafficato ponte Waassertuerm di Lussemburgo, la coesistenza tra la rete tranviaria e il flusso automobilistico ha richiesto una soluzione infrastrutturale d'avanguardia. Scopri come i pannelli per attraversamenti a raso inno possono essere personalizzati e integrati con sistemi antideragliamento, per creare una corsia di emergenza e garantire massima sicurezza. <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/emergenza-traffico-e-protezione-del-deragliamento-con-inno-sul-ponte-wasserturm\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-839 t-838 all\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname ponti\">ponti<\/span><span class=\"batch produktname strail\">strail<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/ponti-Rumaenien-2-300x300.jpg\" class=\"post-thumb\" alt=\"ponti Romania 2\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/ponti-Rumaenien-2-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/ponti-Rumaenien-2-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/ponti-Rumaenien-2-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/ponti-Rumaenien-2.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/modernizzazione-efficiente-con-ponti-e-strail-incrocio\/\">Riqualificazione efficiente di attraversamenti critici con sistemi ponti e strail<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>Due attraversamenti a raso contigui sulla trafficata strada statale di Tecuci, in Romania, rappresentavano uno snodo critico per il traffico della citt\u00e0. Scopri quale soluzione moderna e durevole \u00e8 stata individuata. Nonostante le difficili condizioni locali, l'installazione \u00e8 stata completata in soli due giorni.  <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/modernizzazione-efficiente-con-ponti-e-strail-incrocio\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-842 all\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname ip\">IP<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/IP-Bonassola-2-300x300.jpg\" class=\"post-thumb\" alt=\"Tamponamento del parapetto con pannelli IP sul ponte di Bonassola\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/IP-Bonassola-2-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/IP-Bonassola-2-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/IP-Bonassola-2-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/IP-Bonassola-2.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/laermschutz-in-betonoptik-entlang-der-malerischen-kuestenstrecke-cinque-terre\/\">Barriere antirumore in effetto cemento lungo la pittoresca linea costiera delle Cinque Terre<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>L'operatore ferroviario era alla ricerca di una soluzione di protezione acustica compatta ed esteticamente gradevole per le sezioni di ponte della linea costiera a doppio binario di Bonassola (Cinque Terre). Grazie al montaggio rapido del parapetto e al suo design personalizzato con effetto cemento, \u00e8 stato possibile ridurre il rumore della ferrovia mentre i pannelli si integravano perfettamente nel paesaggio storico. <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/laermschutz-in-betonoptik-entlang-der-malerischen-kuestenstrecke-cinque-terre\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-844 all\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname strailway\">STRAILway<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/STRAILway-Weiche-Loucna-300x300.jpg\" class=\"post-thumb\" alt=\"Deviatoio con traverse polimeriche STRAILway a Loucna\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/STRAILway-Weiche-Loucna-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/STRAILway-Weiche-Loucna-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/STRAILway-Weiche-Loucna-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/STRAILway-Weiche-Loucna.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/traverse-polimeriche-facile-lavorazione-loucna\/\">Le traverse polimeriche convincono per la loro flessibilit\u00e0 nelle lavorazioni a Loucna<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>La prima installazione di traverse polimeriche STRAILway nella Repubblica Ceca \u00e8 avvenuta a Loucna. Il progetto prevedeva la sostituzione delle vecchie traversine in legno. L'installazione rapida e semplice delle traverse polimeriche e il loro design accattivante e di alta qualit\u00e0 hanno convinto il cliente, i responsabili delle ferrovie e dei servizi pubblici coinvolti.  <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/traverse-polimeriche-facile-lavorazione-loucna\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-844 all\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname strailway\">STRAILway<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2026\/01\/STRAILway-Salzgitter-300x300.jpg\" class=\"post-thumb\" alt=\"Traverse STRAILway nell&#039;acciaieria Salzgitter\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2026\/01\/STRAILway-Salzgitter-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/01\/STRAILway-Salzgitter-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/01\/STRAILway-Salzgitter-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/01\/STRAILway-Salzgitter.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/strailway-sostituisce-le-dormeuse-in-legno-in-acciaio\/\">STRAILway sostituisce le traverse in legno in un&#8217;acciaieria<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>15 milioni di tonnellate all'anno: la sfida della Salzgitter Flachstahl. Sottoposta a carichi estremi, la ferrovia dello stabilimento tedesco dice addio alle traverse in legno. Dal 2018, la svolta green e ad alta resistenza porta il nome delle strutture polimeriche STRAILway: un bilancio a lungo termine che dimostra condizioni ancora impeccabili e zero manutenzione. <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/strailway-sostituisce-le-dormeuse-in-legno-in-acciaio\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-844 all\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname strailway_30\">STRAILway 30<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/STRAILway-30-Bozen-300x300.jpg\" class=\"post-thumb\" alt=\"STRAILway 30 Bolzano\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/STRAILway-30-Bozen-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/STRAILway-30-Bozen-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/STRAILway-30-Bozen-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/STRAILway-30-Bozen.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/strailway-30-risparmio-tempo-sudtirolo\/\">STRAILway 30: facilit\u00e0 di montaggio che fa risparmiare tempo in Alto Adige<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>In Alto Adige \u00e8 stato ammodernato un tratto di binari a Renon. Il progetto ha puntato sui prodotti inno per la sicurezza degli attraversamenti a raso e sulle innovative traverse STRAILway 30 per un facile montaggio in loco. <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/strailway-30-risparmio-tempo-sudtirolo\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-838 t-863\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname profil\">profil<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/profil-Kranbahnschiene-Antwerpen-300x300.jpg\" class=\"post-thumb\" alt=\"profil binari delle gru Anversa passaggio sicuro per il traffico logistico\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/profil-Kranbahnschiene-Antwerpen-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/profil-Kranbahnschiene-Antwerpen-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/profil-Kranbahnschiene-Antwerpen-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/profil-Kranbahnschiene-Antwerpen.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/profil-chiude-gole-binari-porto-di-anversa\/\">Porto di Anversa: transito senza ostacoli grazie a profil, i profili per binari<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>Le gigantesche gru per container richiedono canali di scorrimento profondi fino a 55 cm per muoversi sulle rotaie nelle aree portuali. Nel porto di Anversa, queste gole rappresentavano un grave ostacolo e un pericolo per la circolazione. Scopri come il sistema STRAIL profil elimina il problema rendendo i binari perfettamente carrabili e sicuri per veicoli e pedoni, ottimizzando l'intera logistica.  <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/profil-chiude-gole-binari-porto-di-anversa\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-842 all\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname msw_360\">mSW 360<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/mSW-360-Ammertal-300x300.jpg\" class=\"post-thumb\" alt=\"mSW 360 Ammertal\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/mSW-360-Ammertal-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/mSW-360-Ammertal-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/mSW-360-Ammertal-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/mSW-360-Ammertal.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/barriera-antirumore-mini-integra-nel-paesaggio\/\">Mini-barriere antirumore: la protezione acustica che si integra nel paesaggio<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>La riattivazione della ferrovia Ammertal ha posto all'operatore la sfida di proteggere efficacemente i residenti delle aree densamente popolate dal rumore della ferrovia senza deturpare il paesaggio. Scopri come la mini barriera antirumore mSW 360 ha rappresentato la soluzione ottimale e discreta grazie alla sua altezza ridotta e alla sua flessibilit\u00e0 tecnica. <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/barriera-antirumore-mini-integra-nel-paesaggio\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-843 all\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname binario_inerbito\">Binario inerbito<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Rasengleis-Muenchen-300x300.jpg\" class=\"post-thumb\" alt=\"Binario inerbito di Monaco di Baviera\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Rasengleis-Muenchen-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Rasengleis-Muenchen-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Rasengleis-Muenchen-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Rasengleis-Muenchen.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/binario-inerbito-monaco-germania\/\">Rapido da installare e isola dalle correnti: il binario verde STRAILastic \u00e8 la scelta che fa la differenza<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>La Stadtwerke M\u00fcnchen si \u00e8 affidata a 1.880 metri di binario inerbito per la ristrutturazione della linea 25 del tram di Monaco. Scopri come il profilo STRAILastic_R non solo ha soddisfatto gli elevati requisiti di isolamento dalle correnti vaganti, ma ha anche permesso di accelerare il completamento del cantiere grazie al suo montaggio facile e veloce. <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/binario-inerbito-monaco-germania\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-839 t-838 all\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname velo\">velo<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/velo-Preston-feriger-Bahnuebergang-300x300.jpg\" class=\"post-thumb\" alt=\"velo Preston ha terminato l&#039;attraversamento a raso\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/velo-Preston-feriger-Bahnuebergang-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/velo-Preston-feriger-Bahnuebergang-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/velo-Preston-feriger-Bahnuebergang-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/velo-Preston-feriger-Bahnuebergang.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/sicurezza-sulle-bici-72-metri-crea-un-attraversamento-accessibile-per-ciclisti\/\">Sicurezza per oltre 72 metri: velo crea un attraversamento senza barriere per i ciclisti<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>Il fatiscente passaggio a livello di Strand Road a Preston rappresentava un pericolo per la sicurezza, soprattutto per i numerosi ciclisti. Scopri come Ribble Rail non solo ha reso l'attraversamento sicuro e privo di barriere con il sistema velo, ma \u00e8 anche riuscita a completare i lavori lungo 72 metri in sole cinque ore grazie a un montaggio rapido. <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/sicurezza-sulle-bici-72-metri-crea-un-attraversamento-accessibile-per-ciclisti\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-840 t-838\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname pede\">pede<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/pede-Tunnel-Mailand-300x300.jpg\" class=\"post-thumb\" alt=\"pede Tunnel Milano\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/pede-Tunnel-Mailand-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/pede-Tunnel-Mailand-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/pede-Tunnel-Mailand-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/pede-Tunnel-Mailand.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/pede\/\">Soluzione ignifuga pede per le gallerie della metropolitana<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>24 attraversamenti a raso con superficie in gomma ignifuga sono stati installati lungo la rete della metropolitana di Milano. Questi passaggi, appositamente adattati alla sovrastruttura, fungono da via di fuga per i passeggeri in caso di emergenza e contribuiscono quindi in modo significativo alla sicurezza degli utenti. Scopri come la nostra soluzione non solo aumenta la sicurezza, ma semplifica anche la manutenzione dei binari.  <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/pede\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-840 t-838 all\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname grid\">grid<\/span><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/sicurezza-binari-grid-stazione-ulzburg-sued\/\">Sicurezza tra i binari: grid nella stazione di Ulzburg S\u00fcd<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>Protezione efficace contro l'accesso non autorizzato alla sede ferroviaria: grid \u00e8 stato installato su 30 m\u00b2 in sole 3,5 ore presso la stazione di Ulzburg S\u00fcd nello Schleswig-Holstein. Questi pannelli in gomma hanno migliorato il livello di sicurezza dell'area e hanno soddisfatto la AKN Eisenbahn GmbH. <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/sicurezza-binari-grid-stazione-ulzburg-sued\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-842 t-840 all\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname smorzatore\">Smorzatore<\/span><span class=\"batch produktname ip\">IP<\/span><span class=\"batch produktname msw_360\">mSW 360<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Nordhorn-300x300.jpg\" class=\"post-thumb\" alt=\"Soluzioni di isolamento acustico combinate STRAILwave\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Nordhorn-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Nordhorn-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Nordhorn-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/Nordhorn.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/protezione-antirumore-tratta-riattivata-strailwave\/\">Protezione antirumore da un&#8217;unica fonte per una linea ferroviaria riattivata, con la gamma di prodotti combinati STRAILwave<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p><p data-path-to-node=\"8\">A distanza di 45 anni dalla sua chiusura, Nordhorn \u00e8 tornata a essere servita dai treni passeggeri. Per tutelare i residenti e le zone ricreative adiacenti alla tratta riattivata, la Bentheimer Eisenbahn AG ha scelto una soluzione combinata basata su tre prodotti antirumore a marchio STRAILwave: smorzatori per rotaia, pannelli IP e mini-barriera acustica mSW 360. L'intero processo \u00e8 stato portato a termine con successo nel giro di poche settimane.  <\/p><\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/protezione-antirumore-tratta-riattivata-strailwave\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-841 t-838\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname cordolo_strail_d\">Cordolo STRAIL D<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/STRAIL-D-Bordstein-300x300.jpg\" class=\"post-thumb\" alt=\"Cordolo STRAIL D\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/STRAIL-D-Bordstein-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/STRAIL-D-Bordstein-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/STRAIL-D-Bordstein-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/STRAIL-D-Bordstein.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/drenaggio-efficiente-cordolo-strail-d\/\">Drenaggio efficiente con il cordolo STRAIL D<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>Nella provincia di Limburg (Paesi Bassi), caratterizzata da un alto livello di precipitazioni, la combinazione del sistema di passaggi a livello pede e del cordolo di drenaggio STRAIL garantisce un drenaggio efficiente e l'accessibilit\u00e0 alla stazione ferroviaria.<\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/drenaggio-efficiente-cordolo-strail-d\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-838 t-863\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname edge\">edge<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/Bahnsteigkante-edge-Florenz-300x300.jpg\" class=\"post-thumb\" alt=\"Gap filler edge per salire e scendere in sicurezza dal tram\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/Bahnsteigkante-edge-Florenz-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/Bahnsteigkante-edge-Florenz-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/Bahnsteigkante-edge-Florenz-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/Bahnsteigkante-edge-Florenz.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/edge-ueberbrueckt-spalt-zwischen-strassenbahn-und-bahnsteigkante-in-florenz\/\">edge elimina il gap tra tram e banchina a Firenze<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>Tramvia di Firenze: con il sistema robusto e flessibile edge, KRAIBURG STRAIL elimina lo spazio vuoto tra banchina e tram in oltre 15 fermate lungo la linea 1, migliorando la sicurezza dei passeggeri e l'accessibilit\u00e0. <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/edge-ueberbrueckt-spalt-zwischen-strassenbahn-und-bahnsteigkante-in-florenz\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-842\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname msw_1250\">mSW 1250<\/span><span class=\"batch produktname smorzatore\">Smorzatore<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2026\/02\/Bispingen-300x300.jpg\" class=\"post-thumb\" alt=\"barriera antirumore mSW 1250 in combinazione con smorzatore per rotaie Isolamento acustico per aree residenziali\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2026\/02\/Bispingen-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/02\/Bispingen-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/02\/Bispingen-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2026\/02\/Bispingen.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/montaggio-sperimentale-msw-1250-con-smorzatori-rotaia\/\">Montaggio sperimentale della mSW 1250: il debutto insieme ai gi\u00e0 noti smorzatori per rotaia<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>Come proteggere una nuova area residenziale dal rumore della ferrovia senza ostruire la vista? A Bispingen (Germania), con il montaggio sperimentale di mSW 1250 in combinazione con i nostri smorzatori ferroviari, abbiamo dimostrato che \u00e8 possibile ottenere un isolamento acustico molto efficace anche a un'altezza di soli 1,25 metri. <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/montaggio-sperimentale-msw-1250-con-smorzatori-rotaia\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-840 t-838 t-863\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname pede\">pede<\/span><span class=\"batch produktname pedesolar\">pedeSOLAR<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/pedeSOLAR-fuer-sichere-Ueberwege-in-Kaltenkirchen-300x300.jpg\" class=\"post-thumb\" alt=\"pedeSOLAR per attraversare in sicurezza anche al buio\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/pedeSOLAR-fuer-sichere-Ueberwege-in-Kaltenkirchen-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/pedeSOLAR-fuer-sichere-Ueberwege-in-Kaltenkirchen-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/pedeSOLAR-fuer-sichere-Ueberwege-in-Kaltenkirchen-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/pedeSOLAR-fuer-sichere-Ueberwege-in-Kaltenkirchen.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/pedesolar-illumina-passaggio-a-livello\/\">pedeSOLAR illumina la via ai pedoni sui passaggi a livello<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>L'innovativo e sostenibile sistema pedeSOLAR fornisce un'illuminazione fotoluminescente e alimentata a energia solare. Ci\u00f2 supporta l'orientamento di ciclisti e pedoni, soprattutto nelle ore pi\u00f9 buie, come avviene nell'area scolastica di Kaltenkirchen Sud (Germania). L'uso dell'energia solare riduce al minimo il rischio di incidenti al buio e aumenta la sicurezza stradale in modo sostenibile ed ecologico.  <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/pedesolar-illumina-passaggio-a-livello\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><div class=\"strail-post-item\" aria-labelledby=\"t-841 t-838\" data-filtered=\"true\">  <div class=\"wp-block-columns\"><div class=\"wp-block-column\"><div class=\"post-content\"><div class=\"post-image not_blog_u_news\"><span class=\"batch produktname cordolo_strail_tipo_b\">Cordolo STRAIL tipo B<\/span><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/B-Borstein-mit-inno-300x300.jpg\" class=\"post-thumb\" alt=\"Installazione rapida di un attraversamento a raso con mattoni B senza la posa di fondamenta e con inno\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/B-Borstein-mit-inno-300x300.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/B-Borstein-mit-inno-150x150.jpg 150w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/B-Borstein-mit-inno-500x500.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/12\/B-Borstein-mit-inno.jpg 1000w\" sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" data-sizes=\"(max-width: 768px) 500px, (max-width: 1000px) 100vw, 100vw\" \/><\/div><h3 class=\"post-title\"><a href=\"https:\/\/strail.de\/it\/bahnuebergang-mit-inno-und-b-bordstein-in-nur-drei-stunden-montiert\/\">Attraversamento a raso con inno e cordolo B installato in sole tre ore<\/a><\/h3><div class=\"preview-text\"><p class=\"d-none acf_vorschautext\"><\/p>I tempi sempre pi\u00f9 brevi di possesso dei binari nella moderna costruzione dei binari richiedono soluzioni non solo robuste, ma soprattutto rapide da installare. Per questo progetto, la scelta \u00e8 ricaduta sull'efficiente combinazione del sistema inno, indipendente dal passo delle traverse, e del cordolo B senza la posa di fondamenta. Una squadra di quattro persone ha impiegato solo tre ore per montare l'intero attraversamento a raso lungo 5,4 metri. Poich\u00e9 il cordolo B non richiede una fondazione in cemento, il binario ha potuto essere riaperto al traffico subito dopo il montaggio.   <\/div> <a class=\"read_more_refs\" href=\"https:\/\/strail.de\/it\/bahnuebergang-mit-inno-und-b-bordstein-in-nur-drei-stunden-montiert\/\">Maggiori informazioni<\/a>      <\/div>      <\/div>  <\/div><\/div><\/div><div class=\"strail-js-pagination\"><\/div>\n<\/section>\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-c5bbea69 wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns content_columns is-layout-flex wp-container-core-columns-is-layout-99256009 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"2500\" height=\"1875\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante2.jpg\" alt=\"edge profilo pe rbanchine di fermata 2\" class=\"wp-image-4077\" style=\"aspect-ratio:3\/2;object-fit:cover\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante2.jpg 2500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante2-300x225.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante2-1000x750.jpg 1000w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante2-500x375.jpg 500w\" sizes=\"(max-width: 480px) 150px, (max-width: 767px) 150px, (max-width: 1399px) 600px, (max-width: 1999px) 700px, 1000px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-large-font-size\">Soluzioni per le fermate multimodali nel trasporto locale<\/h2>\n\n\n\n<p>edge \u00e8 il profilo <strong>per banchina ideale per le fermate<\/strong> con linee combinate di tram e autobus in cui operano veicoli con diverse larghezze o altezze delle porte. Grazie alla sua <strong>geometria flessibile e al materiale elastico<\/strong>, il sistema pu\u00f2 essere adattato a binari curvi, spazi limitati e altezze di fermata variabili. Il risultato \u00e8 un sistema di <strong>salita comodo e sicuro<\/strong> che funziona bene anche nei punti di coincidenza o nelle aree di accesso ad altre linee del trasporto pubblico urbano ad elevato calpestio.  <\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns content_columns change is-layout-flex wp-container-core-columns-is-layout-99256009 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"813\" height=\"1000\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante-1-813x1000.jpg\" alt=\"edge profilo per banchine di fermata\" class=\"wp-image-4083\" style=\"aspect-ratio:3\/2;object-fit:cover\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante-1-813x1000.jpg 813w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante-1-244x300.jpg 244w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante-1-500x615.jpg 500w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/11\/edge-Bahnsteigkante-1.jpg 1196w\" sizes=\"(max-width: 480px) 150px, (max-width: 767px) 150px, (max-width: 1399px) 600px, (max-width: 1999px) 700px, 1000px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Vantaggi tecnici in fase di montaggio e in esercizio<\/h3>\n\n\n\n<p>Grazie ai moduli preassemblati, i profili possono essere installati anche sul costruito o in tempi ristretti <strong>, senza bisogno di molti macchinari<\/strong>. I profili elastici in gomma riducono l&#8217;usura dei gradini e dei bordi di salita. Il sistema non solo migliora il comfort dei passeggeri, ma <strong>prolunga anche la vita utile dei veicoli e riduce i costi di manutenzione<\/strong> delle fermate nei trasporti municipali.  <\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<aside id=\"ansprechpartner\" class=\"wp-block-group ansprechpartner is-layout-flow wp-block-group-is-layout-flow\" role=\"complementary\">\n<div class=\"wp-block-columns are-vertically-aligned-top is-layout-flex wp-container-core-columns-is-layout-28232c24 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"903\" height=\"619\" src=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/10\/Mitarbeiter-misst-ein-Kunststoffteil-auf-einer-Gleisanlage.jpg\" alt=\"Finden Sie Ihren Ansprechpartner bei STRAIL\" class=\"wp-image-3308\" srcset=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/10\/Mitarbeiter-misst-ein-Kunststoffteil-auf-einer-Gleisanlage.jpg 903w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/10\/Mitarbeiter-misst-ein-Kunststoffteil-auf-einer-Gleisanlage-300x206.jpg 300w,  https:\/\/strail.de\/wp-content\/uploads\/2025\/10\/Mitarbeiter-misst-ein-Kunststoffteil-auf-einer-Gleisanlage-500x343.jpg 500w\" sizes=\"(max-width: 480px) 150px, (max-width: 767px) 150px, (max-width: 1399px) 600px, (max-width: 1999px) 700px, 1000px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top has-accent-2-background-color has-background is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group ansprechpartner_inner_cont has-global-padding is-content-justification-left is-layout-constrained wp-container-core-group-is-layout-3140d370 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-right:0;padding-left:0\">    <h2 id=\"ap-heading\">\n        <span id=\"ap-heading-text\">Trova il tuo <br><mark>referente<\/mark><\/span>\n        <button id=\"ap-close\" style=\"display:none; margin-left:10px;\">\n            <svg width=\"25\" height=\"25\" viewBox=\"0 0 25 25\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M1 1L24 24\" stroke=\"white\" stroke-width=\"2\" stroke-linecap=\"round\"\/><path d=\"M24 1L0.999999 24\" stroke=\"white\" stroke-width=\"2\" stroke-linecap=\"round\"\/>\n            <\/svg>\n        <\/button>\n    <\/h2>\n    <div id=\"ansprechpartner-filter\">\n        <div id=\"custom-land-select\" class=\"custom-dropdown\">\n            <button type=\"button\" class=\"dropdown-toggle\">\n                <span class=\"dropdown-label\">Seleziona il Paese<\/span>\n                <input type=\"text\" class=\"dropdown-search-input\" placeholder=\"Cerca paese\" style=\"display:none;\">\n                <svg id=\"open_search_ansprechp\" class=\"dropdown-icon\" width=\"16\" height=\"15\" viewBox=\"0 0 13 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M13 5.12077L6.5 11.3496L0 5.12077V0.438477L6.5 6.66731L13 0.438477V5.12077Z\" fill=\"black\"\/>\n                <\/svg>\n            <\/button>\n            <ul class=\"dropdown-menu\" style=\"display:none;\">\n                                    <li data-term-id=\"1100\">Africa<\/li>\n                                    <li data-term-id=\"1104\">Albania<\/li>\n                                    <li data-term-id=\"1231\">Algeria<\/li>\n                                    <li data-term-id=\"1295\">America latina<\/li>\n                                    <li data-term-id=\"1352\">Arabia Saudita<\/li>\n                                    <li data-term-id=\"1208\">Australia<\/li>\n                                    <li data-term-id=\"1179\">Austria<\/li>\n                                    <li data-term-id=\"1206\">Azerbaigian<\/li>\n                                    <li data-term-id=\"1210\">Bahrain<\/li>\n                                    <li data-term-id=\"1213\">Belgio<\/li>\n                                    <li data-term-id=\"1216\">Bosnia-Erzegovina<\/li>\n                                    <li data-term-id=\"1219\">Brasile<\/li>\n                                    <li data-term-id=\"1222\">Bulgaria<\/li>\n                                    <li data-term-id=\"1279\">Canada<\/li>\n                                    <li data-term-id=\"1375\">Corea del Sud<\/li>\n                                    <li data-term-id=\"1290\">Croazia<\/li>\n                                    <li data-term-id=\"1229\">Danimarca<\/li>\n                                    <li data-term-id=\"1184\">Egitto<\/li>\n                                    <li data-term-id=\"1188\">Emirati Arabi Uniti<\/li>\n                                    <li data-term-id=\"1236\">Estonia<\/li>\n                                    <li data-term-id=\"1340\">Filippine<\/li>\n                                    <li data-term-id=\"1237\">Finlandia<\/li>\n                                    <li data-term-id=\"1242\">Francia<\/li>\n                                    <li data-term-id=\"1225\">Germania<\/li>\n                                    <li data-term-id=\"1273\">Giappone<\/li>\n                                    <li data-term-id=\"1276\">Giordania<\/li>\n                                    <li data-term-id=\"1248\">Gran Bretagna<\/li>\n                                    <li data-term-id=\"1243\">Grecia<\/li>\n                                    <li data-term-id=\"1251\">Hong Kong<\/li>\n                                    <li data-term-id=\"1252\">India<\/li>\n                                    <li data-term-id=\"1256\">Indonesia<\/li>\n                                    <li data-term-id=\"1268\">Iran<\/li>\n                                    <li data-term-id=\"1260\">Iraq<\/li>\n                                    <li data-term-id=\"1261\">Irlanda<\/li>\n                                    <li data-term-id=\"1264\">Israele<\/li>\n                                    <li data-term-id=\"1271\">Italia<\/li>\n                                    <li data-term-id=\"1285\">Kosovo<\/li>\n                                    <li data-term-id=\"1291\">Kuwait<\/li>\n                                    <li data-term-id=\"1298\">Lettonia<\/li>\n                                    <li data-term-id=\"1302\">Lituania<\/li>\n                                    <li data-term-id=\"1305\">Lussemburgo<\/li>\n                                    <li data-term-id=\"1313\">Macedonia<\/li>\n                                    <li data-term-id=\"1327\">Macedonia del Nord<\/li>\n                                    <li data-term-id=\"1308\">Malesia<\/li>\n                                    <li data-term-id=\"1311\">Marocco<\/li>\n                                    <li data-term-id=\"1317\">Moldavia<\/li>\n                                    <li data-term-id=\"1320\">Montenegro<\/li>\n                                    <li data-term-id=\"1331\">Nord America<\/li>\n                                    <li data-term-id=\"1333\">Norvegia<\/li>\n                                    <li data-term-id=\"1323\">Nuova Zelanda<\/li>\n                                    <li data-term-id=\"1336\">Oman<\/li>\n                                    <li data-term-id=\"1325\">Paesi Bassi<\/li>\n                                    <li data-term-id=\"1342\">Polonia<\/li>\n                                    <li data-term-id=\"1346\">Portogallo<\/li>\n                                    <li data-term-id=\"1283\">Qatar<\/li>\n                                    <li data-term-id=\"1383\">Repubblica Ceca<\/li>\n                                    <li data-term-id=\"1349\">Romania<\/li>\n                                    <li data-term-id=\"1362\">Serbia<\/li>\n                                    <li data-term-id=\"1365\">Singapore<\/li>\n                                    <li data-term-id=\"1368\">Slovacchia<\/li>\n                                    <li data-term-id=\"1369\">Slovenia<\/li>\n                                    <li data-term-id=\"1373\">Spagna<\/li>\n                                    <li data-term-id=\"1197\">Stati Uniti<\/li>\n                                    <li data-term-id=\"1356\">Svezia<\/li>\n                                    <li data-term-id=\"1359\">Svizzera<\/li>\n                                    <li data-term-id=\"1378\">Thailandia<\/li>\n                                    <li data-term-id=\"1385\">Tunisia<\/li>\n                                    <li data-term-id=\"1200\">Turchia<\/li>\n                                    <li data-term-id=\"1195\">Ungheria<\/li>\n                                    <li data-term-id=\"1191\">Uzbekistan<\/li>\n                                    <li data-term-id=\"1186\">Vietnam<\/li>\n                            <\/ul>\n        <\/div>\n        <div id=\"ansprechpartner-results\"><\/div>\n    <\/div>\n    \n<\/div>\n<\/div>\n<\/div>\n<\/aside>\n\n\n\n\n\n<button id=\"ap-badge\">\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"91\" height=\"91\" viewBox=\"0 0 91 91\" fill=\"none\">\n<path d=\"M0 45.5C0 20.371 20.371 0 45.5 0C70.629 0 91 20.371 91 45.5V91H45.5C20.371 91 0 70.629 0 45.5Z\" fill=\"#E65113\"\/>\n<path d=\"M58.48 72.5908L59.88 74.0413C60.4372 74.6193 61.1916 74.9468 61.98 74.953C62.3777 74.9655 62.7743 74.9023 63.15 74.7665C64.2901 74.2766 65.0242 73.1131 65 71.8345V67.5141C65 65.7975 66.3431 64.406 68 64.406C70.7614 64.406 73 62.0867 73 59.2257V40.5768C73 37.7159 70.7614 35.3966 68 35.3966H63V29.1803C63 26.3193 60.7614 24 58 24H28C25.2386 24 23 26.3193 23 29.1803V47.8292C23 50.6901 25.2386 53.0094 28 53.0094C28.5523 53.0094 29 53.4733 29 54.0455V59.4019C29.0003 60.6579 29.7303 61.7903 30.85 62.2717C31.22 62.435 31.6179 62.5196 32.02 62.5204C32.8099 62.5115 33.5645 62.1801 34.12 61.5983L37 58.6145V59.2257C37 62.0867 39.2386 64.406 42 64.406H49.34C50.1354 64.4067 50.8979 64.7346 51.46 65.3177L57 71.0574L58.48 72.5908ZM32.71 60.1375C32.3211 60.5437 31.6879 60.5464 31.2958 60.1435C31.105 59.9474 30.9984 59.6801 31 59.4019V54.0455C31 52.3288 29.6569 50.9373 28 50.9373C26.3431 50.9373 25 49.5458 25 47.8292V29.1803C25 27.4636 26.3431 26.0721 28 26.0721H58C59.6569 26.0721 61 27.4636 61 29.1803V47.8292C61 49.5458 59.6569 50.9373 58 50.9373H42.83C42.0346 50.9381 41.2721 51.266 40.71 51.8491L37.29 55.382L32.71 60.1375ZM71 59.2257C71 60.9424 69.6569 62.3339 68 62.3339C65.2386 62.3339 63 64.6532 63 67.5141V71.8345C63.002 72.2565 62.7568 72.6376 62.38 72.798C62.0084 72.953 61.5834 72.8633 61.3 72.5701L52.88 63.8465C51.9405 62.8756 50.667 62.3314 49.34 62.3339H42C40.3431 62.3339 39 60.9424 39 59.2257V56.5424L42.12 53.3099C42.3087 53.1159 42.5642 53.0079 42.83 53.0094H58C60.7614 53.0094 63 50.6901 63 47.8292V37.4687H68C69.6569 37.4687 71 38.8602 71 40.5768V59.2257ZM43 42.6489C45.2091 42.6489 47 40.7935 47 38.5047C47 36.216 45.2091 34.3605 43 34.3605C40.7909 34.3605 39 36.216 39 38.5047C39 40.7935 40.7909 42.6489 43 42.6489ZM43 36.4326C44.1046 36.4326 45 37.3603 45 38.5047C45 39.6491 44.1046 40.5768 43 40.5768C41.8954 40.5768 41 39.6491 41 38.5047C41 37.3603 41.8954 36.4326 43 36.4326ZM33 34.3605C30.7909 34.3605 29 36.216 29 38.5047C29 40.7935 30.7909 42.6489 33 42.6489C35.2091 42.6489 37 40.7935 37 38.5047C37 36.216 35.2091 34.3605 33 34.3605ZM33 40.5768C31.8954 40.5768 31 39.6491 31 38.5047C31 37.3603 31.8954 36.4326 33 36.4326C34.1046 36.4326 35 37.3603 35 38.5047C35 39.6491 34.1046 40.5768 33 40.5768ZM53 42.6489C55.2091 42.6489 57 40.7935 57 38.5047C57 36.216 55.2091 34.3605 53 34.3605C50.7909 34.3605 49 36.216 49 38.5047C49 40.7935 50.7909 42.6489 53 42.6489ZM53 36.4326C54.1046 36.4326 55 37.3603 55 38.5047C55 39.6491 54.1046 40.5768 53 40.5768C51.8954 40.5768 51 39.6491 51 38.5047C51 37.3603 51.8954 36.4326 53 36.4326Z\" fill=\"white\"\/>\n<\/svg>\n<\/button>\n\n<section class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\" style=\"margin-bottom:var(--wp--preset--spacing--spalten-gap-standart)\">\n<div class=\"wp-block-group linkrow product_img_slider product_img_slider-nowidth mob-2 tab-3 desk-4 slider-gap-16 slider-gap-tab-50 slider-gap-desk-130 slide-1 noloop has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-6bc19566 wp-block-group-is-layout-flex\" style=\"border-radius:15px;padding-top:var(--wp--preset--spacing--30);padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30);box-shadow:var(--wp--preset--shadow--natural)\"><div class=\"inline-svg\"><svg width=\"103\" height=\"104\" viewbox=\"0 0 103 104\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" role=\"img\" aria-label=\"Kraiburg Strail - Blog SVG Icon \"><title>Kraiburg Strail &#8211; Blog SVG Icon <\/title>\n<path d=\"M23.9103 102.143C36.1 102.143 45.9817 92.1651 45.9817 79.857C45.9817 67.5489 36.1 57.5713 23.9103 57.5713C11.7206 57.5713 1.83887 67.5489 1.83887 79.857C1.83887 92.1651 11.7206 102.143 23.9103 102.143Z\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M23.9103 87.2853C28.9893 87.2853 33.1067 83.1279 33.1067 77.9996C33.1067 72.8712 28.9893 68.7139 23.9103 68.7139C18.8312 68.7139 14.7139 72.8712 14.7139 77.9996C14.7139 83.1279 18.8312 87.2853 23.9103 87.2853Z\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M6.67676 93.8043C8.38729 89.1429 11.9187 85.3729 16.3882 83.3486\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M31.4336 83.3486C35.9031 85.3729 39.4345 89.1429 41.145 93.8043\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M51.4999 56.3791V67L66 52.4396C67.0348 51.3947 68.4383 50.8077 69.9017 50.8077H93.8034C97.8666 50.8077 101.161 47.4817 101.161 43.3791V18.286C101.161 14.1834 97.8666 10.8574 93.8034 10.8574H42.3034C38.2403 10.8574 34.9463 14.1834 34.9463 18.286V43.3791C34.9463 47.4817 38.2403 50.8077 42.3034 50.8077H45.982C49.0295 50.8077 51.4999 53.302 51.4999 56.3791Z\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M73.5713 23H91.9641\" stroke=\"#E65113\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M73.5713 38H91.9641\" stroke=\"#E65113\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M91.9641 30.4287H73.5713\" stroke=\"#E65113\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M60 22H48C46.3431 22 45 23.2685 45 24.8333V36.1667C45 37.7315 46.3431 39 48 39H60C61.6569 39 63 37.7315 63 36.1667V24.8333C63 23.2685 61.6569 22 60 22Z\" stroke=\"#E65113\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M46 37.8587L49.5233 34.6871C50.5411 33.771 52.1911 33.771 53.2088 34.6871L58 39\" stroke=\"#E65113\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M53.5 34.5L56.7037 30.8579C57.7264 29.714 59.3847 29.714 60.4074 30.8579L63 33.7574\" stroke=\"#E65113\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M52 30C53.1046 30 54 29.1046 54 28C54 26.8954 53.1046 26 52 26C50.8954 26 50 26.8954 50 28C50 29.1046 50.8954 30 52 30Z\" stroke=\"#E65113\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<\/svg>\n<\/div>\n\n\n<p class=\"has-text-align-center\">Blog<\/p>\n\n\n\n<p class=\"link\"><a href=\"https:\/\/strail.de\/it\/blog\/\" data-type=\"category\" data-id=\"819\">Vai al nostro blog<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-6bc19566 wp-block-group-is-layout-flex\" style=\"border-radius:15px;padding-top:var(--wp--preset--spacing--30);padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30);box-shadow:var(--wp--preset--shadow--natural)\"><div class=\"inline-svg\"><svg width=\"90\" height=\"106\" viewbox=\"0 0 90 106\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" role=\"img\" aria-label=\"Kraiburg Strail - Download SVG Icon \"><title>Kraiburg Strail &#8211; Download SVG Icon <\/title>\n<path d=\"M50.3379 53.9786C52.1379 54.6513 54.0813 55.0386 56.1267 55.0386C62.2428 55.0386 67.5612 51.6547 70.2203 46.7013C70.8953 45.417 72.4294 44.9074 73.8614 45.2947C77.0728 46.1713 80.8775 45.6616 84.6207 42.9913C84.9071 42.7874 85.173 42.5224 85.3775 42.237C90.7777 34.6947 86.9934 26.6632 80.4478 24.4617C79.1796 24.0336 78.3205 22.8309 78.3819 21.5263C78.4023 21.2613 78.4023 20.9963 78.4023 20.7517C78.4023 10.4167 69.8521 2.03857 59.3176 2.03857C53.0788 2.03857 47.5354 4.97396 44.0582 9.51973C43.1377 10.7224 41.44 11.0486 40.1102 10.3147C37.7989 9.01011 35.1191 8.27627 32.2759 8.27627C23.4803 8.27627 16.3619 15.2478 16.3619 23.8705C16.3619 24.0132 16.3824 24.1763 16.3824 24.319C13.0687 23.3405 9.10035 23.8093 5.17287 26.7855C4.90696 26.9893 4.68196 27.234 4.47742 27.5193C-1.61823 36.3051 4.66151 45.682 13.1708 45.682C14.1117 45.682 15.0117 45.5801 15.8503 45.3559C17.1185 45.0501 18.4072 45.6209 19.1435 46.6809C22.0072 50.7782 26.8142 53.4893 32.2757 53.4893C34.6689 53.4893 36.9396 52.9593 38.9646 52.0216\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M51.1358 73.3847H71.8364C73.9636 73.3847 75.682 75.2193 75.682 77.4616V99.8847C75.682 102.127 73.9639 103.962 71.8364 103.962H18.1621C16.0348 103.962 14.3164 102.127 14.3164 99.8847V67.2693C14.3164 65.027 16.0346 63.1924 18.1621 63.1924H32.7261C33.6465 63.1924 34.567 63.5593 35.2625 64.2116L40.5399 69.1855\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M24.5449 85.6152H36.818\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M24.5449 93.769H57.273\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M57.2725 10.1923C57.2725 10.1923 67.4999 8.15382 69.5456 18.3461\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M44.9996 79.4998C48.3887 79.4998 51.136 76.7619 51.136 73.3844C51.136 70.007 48.3887 67.269 44.9996 67.269C41.6106 67.269 38.8633 70.007 38.8633 73.3844C38.8633 76.7619 41.6106 79.4998 44.9996 79.4998Z\" stroke=\"#E65113\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M44.9996 57.077C48.3887 57.077 51.136 54.339 51.136 50.9616C51.136 47.5841 48.3887 44.8462 44.9996 44.8462C41.6106 44.8462 38.8633 47.5841 38.8633 50.9616C38.8633 54.339 41.6106 57.077 44.9996 57.077Z\" stroke=\"#E65113\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M45 57.0771V67.2695\" stroke=\"#E65113\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<\/svg>\n<\/div>\n\n\n<p class=\"has-text-align-center\">Download<\/p>\n\n\n\n<p class=\"link\"><a href=\"https:\/\/strail.de\/it\/area-download\/\" data-type=\"page\" data-id=\"282\">Vai ai nostri download<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-6bc19566 wp-block-group-is-layout-flex\" style=\"border-radius:15px;padding-top:var(--wp--preset--spacing--30);padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30);box-shadow:var(--wp--preset--shadow--natural)\"><div class=\"inline-svg\"><svg width=\"98\" height=\"96\" viewbox=\"0 0 98 96\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" role=\"img\" aria-label=\"Kraiburg Strail - Messen &amp; Events SVG Icon \"><title>Kraiburg Strail &#8211; Messen &amp; Events SVG Icon <\/title>\n<g clip-path=\"url(#clip0_158_6722)\">\n<path d=\"M35.0404 36.8643H6.18375C3.67088 36.8643 1.63379 38.9121 1.63379 41.4383V43.1925C1.63379 45.7187 3.67088 47.7665 6.18375 47.7665H35.0404C37.5533 47.7665 39.5904 45.7187 39.5904 43.1925V41.4383C39.5904 38.9121 37.5533 36.8643 35.0404 36.8643Z\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M37.0872 47.7666H4.13574V88.2307C4.13574 91.4728 6.75021 94.1011 9.97522 94.1011H22.9858C26.8055 94.1011 29.6081 90.4835 28.636 86.7702C27.3362 81.8046 26.4289 74.9626 27.9108 67.1678C29.8104 57.1767 34.6865 50.6112 37.0872 47.7666Z\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M74.0011 28.0585C81.2575 28.0585 87.1399 22.1449 87.1399 14.8501C87.1399 7.55523 81.2575 1.6416 74.0011 1.6416C66.7448 1.6416 60.8623 7.55523 60.8623 14.8501C60.8623 22.1449 66.7448 28.0585 74.0011 28.0585Z\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M86.9256 71.2396H88.872C93.0181 71.2396 96.3661 67.8738 96.3661 63.7058V45.3901C96.3661 35.8213 88.6579 28.0527 79.1397 28.0527H68.8621C59.3437 28.0527 51.6357 35.8213 51.6357 45.3901V63.7058C51.6357 67.8738 54.9837 71.2396 59.1298 71.2396H61.6992\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M86.9312 52.1689V94.3102H61.6963V52.1689\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M74.418 68.9414V93.6812\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M17.4834 36.6549L23.1698 17.5834C23.845 15.3188 25.9182 13.7676 28.2701 13.7676\" stroke=\"#E65113\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M37.5486 10H32.4514C30.5452 10 29 11.5027 29 13.3564V14.6436C29 16.4973 30.5452 18 32.4514 18H37.5486C39.4548 18 41 16.4973 41 14.6436V13.3564C41 11.5027 39.4548 10 37.5486 10Z\" stroke=\"#E65113\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M56.8457 94.3579L91.7997 94.2695\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<\/g>\n<defs>\n<clippath id=\"clip0_158_6722\">\n<rect width=\"98\" height=\"96\" fill=\"white\"><\/rect>\n<\/clippath>\n<\/defs>\n<\/svg>\n<\/div>\n\n\n<p class=\"has-text-align-center\">Fiere ed eventi<\/p>\n\n\n\n<p class=\"link\"><a href=\"https:\/\/strail.de\/it\/fiere-eventi\/\" data-type=\"page\" data-id=\"278\">Vai a fiere ed eventi<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-center is-layout-flex wp-container-core-group-is-layout-6bc19566 wp-block-group-is-layout-flex\" style=\"border-radius:15px;padding-top:var(--wp--preset--spacing--30);padding-right:var(--wp--preset--spacing--30);padding-bottom:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30);box-shadow:var(--wp--preset--shadow--natural)\"><div class=\"inline-svg\"><svg width=\"98\" height=\"98\" viewbox=\"0 0 98 98\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" role=\"img\" aria-label=\"Kraiburg Strail - Kontakt SVG Icon \"><title>Kraiburg Strail &#8211; Kontakt SVG Icon <\/title>\n<path d=\"M75 9.66667V53C75 57.7864 71.1022 61.6667 66.2941 61.6667H30.5L22.7647 79L9.70588 61.6667C4.89784 61.6667 1 57.7864 1 53V9.66667C1 4.88028 4.89784 1 9.70588 1H66.2941C71.1022 1 75 4.88028 75 9.66667Z\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<path d=\"M75.1762 18H88.2705C93.0916 18 97 21.93 97 26.7778V70.6667C97 75.5144 93.0916 79.4444 88.2705 79.4444L75.1762 97L69.5 79.4444H31.5286C28.9313 79.4444 26.599 78.304 25 76.4938\" stroke=\"black\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n<circle cx=\"21.5\" cy=\"30.5\" r=\"4.5\" stroke=\"#E65113\" stroke-width=\"2\"><\/circle>\n<circle cx=\"55.5\" cy=\"30.5\" r=\"4.5\" stroke=\"#E65113\" stroke-width=\"2\"><\/circle>\n<circle cx=\"38.5\" cy=\"30.5\" r=\"6.5\" stroke=\"#E65113\" stroke-width=\"2\"><\/circle>\n<\/svg>\n<\/div>\n\n\n<p class=\"has-text-align-center\">Contatti<\/p>\n\n\n\n<p class=\"link\"><a href=\"https:\/\/strail.de\/it\/contatti-interlocutori\/\" data-type=\"page\" data-id=\"284\">Vai alla pagina dei contatti<\/a><\/p>\n<\/div>\n<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>edge Profilo in gomma per banchine di fermata senza barriere, per maggiore comfort e protezione edge \u00e8 un profilo in gomma per banchine sviluppato appositamente per le fermate dei trasporti pubblici. Permette di salire e scendere in modo confortevole e senza barriere, anche con diversi tipi di veicoli e geometrie di piattaforma. Il materiale flessibile [&hellip;]<\/p>","protected":false},"author":2,"featured_media":11211,"parent":12134,"menu_order":118,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11210","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soluzione speciale per sistemi di attraversamento a raso - edge<\/title>\n<meta name=\"description\" content=\"Soluzione speciale per sistemi di attraversamento a raso - edge - profilo in gomma per banchine di fermata senza barriere. Protegge i veicoli e consente di salire e scendere comodamente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/strail.de\/it\/sistemi-di-attraversamento-a-raso\/soluzioni-speciali\/edge\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soluzione speciale per sistemi di attraversamento a raso - edge\" \/>\n<meta property=\"og:description\" content=\"Soluzione speciale per sistemi di attraversamento a raso - edge - profilo in gomma per banchine di fermata senza barriere. Protegge i veicoli e consente di salire e scendere comodamente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/strail.de\/it\/sistemi-di-attraversamento-a-raso\/soluzioni-speciali\/edge\/\" \/>\n<meta property=\"og:site_name\" content=\"KRAIBURG STRAIL\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T07:44:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/strail.de\/wp-content\/uploads\/2025\/10\/edge.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1333\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/strail.de\\\/it\\\/sistemi-di-attraversamento-a-raso\\\/soluzioni-speciali\\\/edge\\\/\",\"url\":\"https:\\\/\\\/strail.de\\\/it\\\/sistemi-di-attraversamento-a-raso\\\/soluzioni-speciali\\\/edge\\\/\",\"name\":\"Soluzione speciale per sistemi di attraversamento a raso - edge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/strail.de\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/strail.de\\\/it\\\/sistemi-di-attraversamento-a-raso\\\/soluzioni-speciali\\\/edge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/strail.de\\\/it\\\/sistemi-di-attraversamento-a-raso\\\/soluzioni-speciali\\\/edge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/strail.de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/edge.jpg\",\"datePublished\":\"2025-07-30T07:00:18+00:00\",\"dateModified\":\"2026-06-02T07:44:05+00:00\",\"description\":\"Soluzione speciale per sistemi di attraversamento a raso - edge - profilo in gomma per banchine di fermata senza barriere. Protegge i veicoli e consente di salire e scendere comodamente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/strail.de\\\/it\\\/sistemi-di-attraversamento-a-raso\\\/soluzioni-speciali\\\/edge\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/strail.de\\\/it\\\/sistemi-di-attraversamento-a-raso\\\/soluzioni-speciali\\\/edge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/strail.de\\\/it\\\/sistemi-di-attraversamento-a-raso\\\/soluzioni-speciali\\\/edge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/strail.de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/edge.jpg\",\"contentUrl\":\"https:\\\/\\\/strail.de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/edge.jpg\",\"width\":1333,\"height\":1000,\"caption\":\"edge - profilo in gomma per banchine di fermata senza barriere, per maggiore comfort e protezione.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/strail.de\\\/it\\\/sistemi-di-attraversamento-a-raso\\\/soluzioni-speciali\\\/edge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/strail.de\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sistemi di attraversamento a raso\",\"item\":\"https:\\\/\\\/strail.de\\\/it\\\/sistemi-di-attraversamento-a-raso\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Soluzioni speciali\",\"item\":\"https:\\\/\\\/strail.de\\\/it\\\/sistemi-di-attraversamento-a-raso\\\/soluzioni-speciali\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"edge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/strail.de\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/strail.de\\\/it\\\/\",\"name\":\"KRAIBURG STRAIL\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/strail.de\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/strail.de\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/strail.de\\\/it\\\/#organization\",\"name\":\"KRAIBURG STRAIL\",\"url\":\"https:\\\/\\\/strail.de\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/strail.de\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/strail.de\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/STRAIL-Logo.svg\",\"contentUrl\":\"https:\\\/\\\/strail.de\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/STRAIL-Logo.svg\",\"caption\":\"KRAIBURG STRAIL\"},\"image\":{\"@id\":\"https:\\\/\\\/strail.de\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"address\":{\"@type\":\"PostalAddress\",\"addressCountry\":\"DE\"},\"location\":[{\"@type\":\"Place\",\"name\":null,\"address\":{\"@type\":\"PostalAddress\",\"addressCountry\":\"DE\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soluzione speciale per sistemi di attraversamento a raso - edge","description":"Soluzione speciale per sistemi di attraversamento a raso - edge - profilo in gomma per banchine di fermata senza barriere. Protegge i veicoli e consente di salire e scendere comodamente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/strail.de\/it\/sistemi-di-attraversamento-a-raso\/soluzioni-speciali\/edge\/","og_locale":"it_IT","og_type":"article","og_title":"Soluzione speciale per sistemi di attraversamento a raso - edge","og_description":"Soluzione speciale per sistemi di attraversamento a raso - edge - profilo in gomma per banchine di fermata senza barriere. Protegge i veicoli e consente di salire e scendere comodamente.","og_url":"https:\/\/strail.de\/it\/sistemi-di-attraversamento-a-raso\/soluzioni-speciali\/edge\/","og_site_name":"KRAIBURG STRAIL","article_modified_time":"2026-06-02T07:44:05+00:00","og_image":[{"width":1333,"height":1000,"url":"https:\/\/strail.de\/wp-content\/uploads\/2025\/10\/edge.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/strail.de\/it\/sistemi-di-attraversamento-a-raso\/soluzioni-speciali\/edge\/","url":"https:\/\/strail.de\/it\/sistemi-di-attraversamento-a-raso\/soluzioni-speciali\/edge\/","name":"Soluzione speciale per sistemi di attraversamento a raso - edge","isPartOf":{"@id":"https:\/\/strail.de\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/strail.de\/it\/sistemi-di-attraversamento-a-raso\/soluzioni-speciali\/edge\/#primaryimage"},"image":{"@id":"https:\/\/strail.de\/it\/sistemi-di-attraversamento-a-raso\/soluzioni-speciali\/edge\/#primaryimage"},"thumbnailUrl":"https:\/\/strail.de\/wp-content\/uploads\/2025\/10\/edge.jpg","datePublished":"2025-07-30T07:00:18+00:00","dateModified":"2026-06-02T07:44:05+00:00","description":"Soluzione speciale per sistemi di attraversamento a raso - edge - profilo in gomma per banchine di fermata senza barriere. Protegge i veicoli e consente di salire e scendere comodamente.","breadcrumb":{"@id":"https:\/\/strail.de\/it\/sistemi-di-attraversamento-a-raso\/soluzioni-speciali\/edge\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/strail.de\/it\/sistemi-di-attraversamento-a-raso\/soluzioni-speciali\/edge\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/strail.de\/it\/sistemi-di-attraversamento-a-raso\/soluzioni-speciali\/edge\/#primaryimage","url":"https:\/\/strail.de\/wp-content\/uploads\/2025\/10\/edge.jpg","contentUrl":"https:\/\/strail.de\/wp-content\/uploads\/2025\/10\/edge.jpg","width":1333,"height":1000,"caption":"edge - profilo in gomma per banchine di fermata senza barriere, per maggiore comfort e protezione."},{"@type":"BreadcrumbList","@id":"https:\/\/strail.de\/it\/sistemi-di-attraversamento-a-raso\/soluzioni-speciali\/edge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/strail.de\/it\/"},{"@type":"ListItem","position":2,"name":"Sistemi di attraversamento a raso","item":"https:\/\/strail.de\/it\/sistemi-di-attraversamento-a-raso\/"},{"@type":"ListItem","position":3,"name":"Soluzioni speciali","item":"https:\/\/strail.de\/it\/sistemi-di-attraversamento-a-raso\/soluzioni-speciali\/"},{"@type":"ListItem","position":4,"name":"edge"}]},{"@type":"WebSite","@id":"https:\/\/strail.de\/it\/#website","url":"https:\/\/strail.de\/it\/","name":"KRAIBURG STRAIL","description":"","publisher":{"@id":"https:\/\/strail.de\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/strail.de\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/strail.de\/it\/#organization","name":"KRAIBURG STRAIL","url":"https:\/\/strail.de\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/strail.de\/it\/#\/schema\/logo\/image\/","url":"https:\/\/strail.de\/wp-content\/uploads\/2025\/08\/STRAIL-Logo.svg","contentUrl":"https:\/\/strail.de\/wp-content\/uploads\/2025\/08\/STRAIL-Logo.svg","caption":"KRAIBURG STRAIL"},"image":{"@id":"https:\/\/strail.de\/it\/#\/schema\/logo\/image\/"},"address":{"@type":"PostalAddress","addressCountry":"DE"},"location":[{"@type":"Place","name":null,"address":{"@type":"PostalAddress","addressCountry":"DE"}}]}]}},"_links":{"self":[{"href":"https:\/\/strail.de\/it\/wp-json\/wp\/v2\/pages\/11210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strail.de\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/strail.de\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/strail.de\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/strail.de\/it\/wp-json\/wp\/v2\/comments?post=11210"}],"version-history":[{"count":4,"href":"https:\/\/strail.de\/it\/wp-json\/wp\/v2\/pages\/11210\/revisions"}],"predecessor-version":[{"id":12716,"href":"https:\/\/strail.de\/it\/wp-json\/wp\/v2\/pages\/11210\/revisions\/12716"}],"up":[{"embeddable":true,"href":"https:\/\/strail.de\/it\/wp-json\/wp\/v2\/pages\/12134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strail.de\/it\/wp-json\/wp\/v2\/media\/11211"}],"wp:attachment":[{"href":"https:\/\/strail.de\/it\/wp-json\/wp\/v2\/media?parent=11210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}